{"id":1890,"date":"2026-05-11T13:01:53","date_gmt":"2026-05-11T13:01:53","guid":{"rendered":"https:\/\/www.africascoop.net\/?p=1890"},"modified":"2026-05-11T13:01:58","modified_gmt":"2026-05-11T13:01:58","slug":"mali-le-directeur-regional-de-lortm-kidal-raconte-son-arrestation-et-son-exfiltration-de-la-ville","status":"publish","type":"post","link":"https:\/\/www.africascoop.net\/index.php\/2026\/05\/11\/mali-le-directeur-regional-de-lortm-kidal-raconte-son-arrestation-et-son-exfiltration-de-la-ville\/","title":{"rendered":"Mali : le directeur r\u00e9gional de l\u2019ORTM Kidal raconte son arrestation et son exfiltration de la ville"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.africascoop.net\/wp-content\/uploads\/2026\/05\/drones-civils-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-1024x576.jpg\" alt=\"\" class=\"wp-image-1891\" srcset=\"https:\/\/www.africascoop.net\/wp-content\/uploads\/2026\/05\/drones-civils-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-1024x576.jpg 1024w, https:\/\/www.africascoop.net\/wp-content\/uploads\/2026\/05\/drones-civils-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-300x169.jpg 300w, https:\/\/www.africascoop.net\/wp-content\/uploads\/2026\/05\/drones-civils-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-768x432.jpg 768w, https:\/\/www.africascoop.net\/wp-content\/uploads\/2026\/05\/drones-civils-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere.jpg 1366w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong><em>Dans un t\u00e9moignage in\u00e9dit sur ORTM, Sidi Elmehdi Ag Backa est revenu sur les \u00e9v\u00e9nements survenus \u00e0 Kidal le 25 avril dernier, marqu\u00e9s par des affrontements arm\u00e9s et l\u2019entr\u00e9e de groupes arm\u00e9s dans la ville.<\/em><\/strong><\/p>\n\n\n\n<p>Selon lui, les premiers tirs ont \u00e9clat\u00e9 tr\u00e8s t\u00f4t dans la matin\u00e9e. \u00ab Apr\u00e8s deux heures, nous avons constat\u00e9 la pr\u00e9sence de groupes arm\u00e9s terroristes et s\u00e9paratistes \u00e0 l\u2019int\u00e9rieur de la ville \u00bb, explique-t-il, soulignant une d\u00e9gradation rapide de la situation s\u00e9curitaire.<\/p>\n\n\n\n<p>Le responsable de l\u2019ORTM affirme qu\u2019apr\u00e8s le retrait des autorit\u00e9s administratives vers le camp militaire, il s\u2019est retrouv\u00e9 bloqu\u00e9 en ville avec sa famille. Quelques heures plus tard, des hommes arm\u00e9s auraient fait irruption \u00e0 son domicile avant de l\u2019interpeller devant ses proches.<\/p>\n\n\n\n<p>\u00ab Ils ont escalad\u00e9 le mur pour entrer chez moi. J\u2019entends encore les cris de mes enfants qui ne comprenaient pas ce qui se passait \u00bb, confie-t-il.<\/p>\n\n\n\n<p>Transport\u00e9 dans d\u2019anciens logements sociaux abandonn\u00e9s, il dit avoir subi des pressions et des intimidations avant d\u2019\u00eatre finalement transf\u00e9r\u00e9 chez le maire de la ville gr\u00e2ce \u00e0 l\u2019intervention de membres de sa communaut\u00e9.<\/p>\n\n\n\n<p>Toujours selon son r\u00e9cit, cette p\u00e9riode lui aurait permis de retrouver son cadreur et de pr\u00e9parer leur d\u00e9part clandestin de Kidal. Les deux hommes auraient ensuite rejoint l\u2019Alg\u00e9rie, puis le Niger, avant de regagner Bamako.<\/p>\n\n\n\n<p>Au cours de cet entretien, Sidi Elmehdi Ag Backa a \u00e9galement contest\u00e9 certaines informations relay\u00e9es sur la situation militaire dans le nord du Mali. Il affirme notamment que l\u2019arm\u00e9e malienne contr\u00f4lerait \u00ab totalement \u00bb les secteurs d\u2019Anefis et d\u2019Aguelhoc, situ\u00e9s respectivement \u00e0 112 et 150 kilom\u00e8tres de Kidal.<\/p>\n\n\n\n<p>Le journaliste affirme aussi avoir entendu, durant sa d\u00e9tention, des discussions faisant \u00e9tat d\u2019une vaste coalition impliquant des combattants terroristes, s\u00e9paratistes et des mercenaires \u00e9trangers venus de plusieurs pays de la sous-r\u00e9gion et du Sahel.<\/p>\n\n\n\n<p>Selon lui, l\u2019objectif des assaillants d\u00e9passait la seule ville de Kidal et visait \u00ab l\u2019institution militaire malienne \u00bb ainsi qu\u2019une d\u00e9stabilisation g\u00e9n\u00e9rale du pays. Il \u00e9voque \u00e9galement un suppos\u00e9 projet visant \u00e0 attiser les tensions communautaires entre plusieurs composantes de la soci\u00e9t\u00e9 malienne.<\/p>\n\n\n\n<p>Par Djibrilla Tour\u00e9<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans un t\u00e9moignage in\u00e9dit sur ORTM, Sidi Elmehdi Ag Backa est revenu sur les \u00e9v\u00e9nements survenus \u00e0 Kidal<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36,7],"tags":[],"class_list":["post-1890","post","type-post","status-publish","format-standard","hentry","category-exclusif","category-securite"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mali : le directeur r\u00e9gional de l\u2019ORTM Kidal raconte son arrestation et son exfiltration de la ville - Actualit\u00e9s Africaines<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.africascoop.net\/index.php\/2026\/05\/11\/mali-le-directeur-regional-de-lortm-kidal-raconte-son-arrestation-et-son-exfiltration-de-la-ville\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mali : le directeur r\u00e9gional de l\u2019ORTM Kidal raconte son arrestation et son exfiltration de la ville - Actualit\u00e9s Africaines\" \/>\n<meta property=\"og:description\" content=\"Dans un t\u00e9moignage in\u00e9dit sur ORTM, Sidi Elmehdi Ag Backa est revenu sur les \u00e9v\u00e9nements survenus \u00e0 Kidal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.africascoop.net\/index.php\/2026\/05\/11\/mali-le-directeur-regional-de-lortm-kidal-raconte-son-arrestation-et-son-exfiltration-de-la-ville\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualit\u00e9s Africaines\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-11T13:01:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T13:01:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.africascoop.net\/wp-content\/uploads\/2026\/05\/drones-civils-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1366\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Africascoop\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Africascoop\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.africascoop.net\/index.php\/2026\/05\/11\/mali-le-directeur-regional-de-lortm-kidal-raconte-son-arrestation-et-son-exfiltration-de-la-ville\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.africascoop.net\/index.php\/2026\/05\/11\/mali-le-directeur-regional-de-lortm-kidal-raconte-son-arrestation-et-son-exfiltration-de-la-ville\/\"},\"author\":{\"name\":\"Africascoop\",\"@id\":\"https:\/\/www.africascoop.net\/#\/schema\/person\/2cbcc632c110d739d93a6b196c67230a\"},\"headline\":\"Mali : le directeur r\u00e9gional de l\u2019ORTM Kidal raconte son arrestation et son exfiltration de la ville\",\"datePublished\":\"2026-05-11T13:01:53+00:00\",\"dateModified\":\"2026-05-11T13:01:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.africascoop.net\/index.php\/2026\/05\/11\/mali-le-directeur-regional-de-lortm-kidal-raconte-son-arrestation-et-son-exfiltration-de-la-ville\/\"},\"wordCount\":404,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.africascoop.net\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.africascoop.net\/index.php\/2026\/05\/11\/mali-le-directeur-regional-de-lortm-kidal-raconte-son-arrestation-et-son-exfiltration-de-la-ville\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.africascoop.net\/wp-content\/uploads\/2026\/05\/drones-civils-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-1024x576.jpg\",\"articleSection\":[\"Exclusif\",\"S\u00e9curit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.africascoop.net\/index.php\/2026\/05\/11\/mali-le-directeur-regional-de-lortm-kidal-raconte-son-arrestation-et-son-exfiltration-de-la-ville\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.africascoop.net\/index.php\/2026\/05\/11\/mali-le-directeur-regional-de-lortm-kidal-raconte-son-arrestation-et-son-exfiltration-de-la-ville\/\",\"url\":\"https:\/\/www.africascoop.net\/index.php\/2026\/05\/11\/mali-le-directeur-regional-de-lortm-kidal-raconte-son-arrestation-et-son-exfiltration-de-la-ville\/\",\"name\":\"Mali : le directeur r\u00e9gional de l\u2019ORTM Kidal raconte son arrestation et son exfiltration de la ville - Actualit\u00e9s Africaines\",\"isPartOf\":{\"@id\":\"https:\/\/www.africascoop.net\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.africascoop.net\/index.php\/2026\/05\/11\/mali-le-directeur-regional-de-lortm-kidal-raconte-son-arrestation-et-son-exfiltration-de-la-ville\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.africascoop.net\/index.php\/2026\/05\/11\/mali-le-directeur-regional-de-lortm-kidal-raconte-son-arrestation-et-son-exfiltration-de-la-ville\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.africascoop.net\/wp-content\/uploads\/2026\/05\/drones-civils-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-1024x576.jpg\",\"datePublished\":\"2026-05-11T13:01:53+00:00\",\"dateModified\":\"2026-05-11T13:01:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.africascoop.net\/index.php\/2026\/05\/11\/mali-le-directeur-regional-de-lortm-kidal-raconte-son-arrestation-et-son-exfiltration-de-la-ville\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.africascoop.net\/index.php\/2026\/05\/11\/mali-le-directeur-regional-de-lortm-kidal-raconte-son-arrestation-et-son-exfiltration-de-la-ville\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africascoop.net\/index.php\/2026\/05\/11\/mali-le-directeur-regional-de-lortm-kidal-raconte-son-arrestation-et-son-exfiltration-de-la-ville\/#primaryimage\",\"url\":\"https:\/\/www.africascoop.net\/wp-content\/uploads\/2026\/05\/drones-civils-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere.jpg\",\"contentUrl\":\"https:\/\/www.africascoop.net\/wp-content\/uploads\/2026\/05\/drones-civils-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere.jpg\",\"width\":1366,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.africascoop.net\/index.php\/2026\/05\/11\/mali-le-directeur-regional-de-lortm-kidal-raconte-son-arrestation-et-son-exfiltration-de-la-ville\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.africascoop.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mali : le directeur r\u00e9gional de l\u2019ORTM Kidal raconte son arrestation et son exfiltration de la ville\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.africascoop.net\/#website\",\"url\":\"https:\/\/www.africascoop.net\/\",\"name\":\"Actualit\u00e9s Africaines\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.africascoop.net\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.africascoop.net\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.africascoop.net\/#organization\",\"name\":\"Actualit\u00e9s Africaines\",\"url\":\"https:\/\/www.africascoop.net\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africascoop.net\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.africascoop.net\/wp-content\/uploads\/2025\/09\/cropped-logo-2.jpg\",\"contentUrl\":\"https:\/\/www.africascoop.net\/wp-content\/uploads\/2025\/09\/cropped-logo-2.jpg\",\"width\":945,\"height\":591,\"caption\":\"Actualit\u00e9s Africaines\"},\"image\":{\"@id\":\"https:\/\/www.africascoop.net\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.africascoop.net\/#\/schema\/person\/2cbcc632c110d739d93a6b196c67230a\",\"name\":\"Africascoop\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.africascoop.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/230d851f5173f64fe9487b948bd2daf02707ef49aea942bc1bdad649c82025b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/230d851f5173f64fe9487b948bd2daf02707ef49aea942bc1bdad649c82025b9?s=96&d=mm&r=g\",\"caption\":\"Africascoop\"},\"url\":\"https:\/\/www.africascoop.net\/index.php\/author\/jul\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mali : le directeur r\u00e9gional de l\u2019ORTM Kidal raconte son arrestation et son exfiltration de la ville - Actualit\u00e9s Africaines","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.africascoop.net\/index.php\/2026\/05\/11\/mali-le-directeur-regional-de-lortm-kidal-raconte-son-arrestation-et-son-exfiltration-de-la-ville\/","og_locale":"fr_FR","og_type":"article","og_title":"Mali : le directeur r\u00e9gional de l\u2019ORTM Kidal raconte son arrestation et son exfiltration de la ville - Actualit\u00e9s Africaines","og_description":"Dans un t\u00e9moignage in\u00e9dit sur ORTM, Sidi Elmehdi Ag Backa est revenu sur les \u00e9v\u00e9nements survenus \u00e0 Kidal","og_url":"https:\/\/www.africascoop.net\/index.php\/2026\/05\/11\/mali-le-directeur-regional-de-lortm-kidal-raconte-son-arrestation-et-son-exfiltration-de-la-ville\/","og_site_name":"Actualit\u00e9s Africaines","article_published_time":"2026-05-11T13:01:53+00:00","article_modified_time":"2026-05-11T13:01:58+00:00","og_image":[{"width":1366,"height":768,"url":"https:\/\/www.africascoop.net\/wp-content\/uploads\/2026\/05\/drones-civils-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere.jpg","type":"image\/jpeg"}],"author":"Africascoop","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Africascoop","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.africascoop.net\/index.php\/2026\/05\/11\/mali-le-directeur-regional-de-lortm-kidal-raconte-son-arrestation-et-son-exfiltration-de-la-ville\/#article","isPartOf":{"@id":"https:\/\/www.africascoop.net\/index.php\/2026\/05\/11\/mali-le-directeur-regional-de-lortm-kidal-raconte-son-arrestation-et-son-exfiltration-de-la-ville\/"},"author":{"name":"Africascoop","@id":"https:\/\/www.africascoop.net\/#\/schema\/person\/2cbcc632c110d739d93a6b196c67230a"},"headline":"Mali : le directeur r\u00e9gional de l\u2019ORTM Kidal raconte son arrestation et son exfiltration de la ville","datePublished":"2026-05-11T13:01:53+00:00","dateModified":"2026-05-11T13:01:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.africascoop.net\/index.php\/2026\/05\/11\/mali-le-directeur-regional-de-lortm-kidal-raconte-son-arrestation-et-son-exfiltration-de-la-ville\/"},"wordCount":404,"commentCount":0,"publisher":{"@id":"https:\/\/www.africascoop.net\/#organization"},"image":{"@id":"https:\/\/www.africascoop.net\/index.php\/2026\/05\/11\/mali-le-directeur-regional-de-lortm-kidal-raconte-son-arrestation-et-son-exfiltration-de-la-ville\/#primaryimage"},"thumbnailUrl":"https:\/\/www.africascoop.net\/wp-content\/uploads\/2026\/05\/drones-civils-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-1024x576.jpg","articleSection":["Exclusif","S\u00e9curit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.africascoop.net\/index.php\/2026\/05\/11\/mali-le-directeur-regional-de-lortm-kidal-raconte-son-arrestation-et-son-exfiltration-de-la-ville\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.africascoop.net\/index.php\/2026\/05\/11\/mali-le-directeur-regional-de-lortm-kidal-raconte-son-arrestation-et-son-exfiltration-de-la-ville\/","url":"https:\/\/www.africascoop.net\/index.php\/2026\/05\/11\/mali-le-directeur-regional-de-lortm-kidal-raconte-son-arrestation-et-son-exfiltration-de-la-ville\/","name":"Mali : le directeur r\u00e9gional de l\u2019ORTM Kidal raconte son arrestation et son exfiltration de la ville - Actualit\u00e9s Africaines","isPartOf":{"@id":"https:\/\/www.africascoop.net\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.africascoop.net\/index.php\/2026\/05\/11\/mali-le-directeur-regional-de-lortm-kidal-raconte-son-arrestation-et-son-exfiltration-de-la-ville\/#primaryimage"},"image":{"@id":"https:\/\/www.africascoop.net\/index.php\/2026\/05\/11\/mali-le-directeur-regional-de-lortm-kidal-raconte-son-arrestation-et-son-exfiltration-de-la-ville\/#primaryimage"},"thumbnailUrl":"https:\/\/www.africascoop.net\/wp-content\/uploads\/2026\/05\/drones-civils-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-1024x576.jpg","datePublished":"2026-05-11T13:01:53+00:00","dateModified":"2026-05-11T13:01:58+00:00","breadcrumb":{"@id":"https:\/\/www.africascoop.net\/index.php\/2026\/05\/11\/mali-le-directeur-regional-de-lortm-kidal-raconte-son-arrestation-et-son-exfiltration-de-la-ville\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.africascoop.net\/index.php\/2026\/05\/11\/mali-le-directeur-regional-de-lortm-kidal-raconte-son-arrestation-et-son-exfiltration-de-la-ville\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africascoop.net\/index.php\/2026\/05\/11\/mali-le-directeur-regional-de-lortm-kidal-raconte-son-arrestation-et-son-exfiltration-de-la-ville\/#primaryimage","url":"https:\/\/www.africascoop.net\/wp-content\/uploads\/2026\/05\/drones-civils-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere.jpg","contentUrl":"https:\/\/www.africascoop.net\/wp-content\/uploads\/2026\/05\/drones-civils-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere-Recupere.jpg","width":1366,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/www.africascoop.net\/index.php\/2026\/05\/11\/mali-le-directeur-regional-de-lortm-kidal-raconte-son-arrestation-et-son-exfiltration-de-la-ville\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.africascoop.net\/"},{"@type":"ListItem","position":2,"name":"Mali : le directeur r\u00e9gional de l\u2019ORTM Kidal raconte son arrestation et son exfiltration de la ville"}]},{"@type":"WebSite","@id":"https:\/\/www.africascoop.net\/#website","url":"https:\/\/www.africascoop.net\/","name":"Actualit\u00e9s Africaines","description":"","publisher":{"@id":"https:\/\/www.africascoop.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.africascoop.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.africascoop.net\/#organization","name":"Actualit\u00e9s Africaines","url":"https:\/\/www.africascoop.net\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africascoop.net\/#\/schema\/logo\/image\/","url":"https:\/\/www.africascoop.net\/wp-content\/uploads\/2025\/09\/cropped-logo-2.jpg","contentUrl":"https:\/\/www.africascoop.net\/wp-content\/uploads\/2025\/09\/cropped-logo-2.jpg","width":945,"height":591,"caption":"Actualit\u00e9s Africaines"},"image":{"@id":"https:\/\/www.africascoop.net\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.africascoop.net\/#\/schema\/person\/2cbcc632c110d739d93a6b196c67230a","name":"Africascoop","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.africascoop.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/230d851f5173f64fe9487b948bd2daf02707ef49aea942bc1bdad649c82025b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/230d851f5173f64fe9487b948bd2daf02707ef49aea942bc1bdad649c82025b9?s=96&d=mm&r=g","caption":"Africascoop"},"url":"https:\/\/www.africascoop.net\/index.php\/author\/jul\/"}]}},"_links":{"self":[{"href":"https:\/\/www.africascoop.net\/index.php\/wp-json\/wp\/v2\/posts\/1890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.africascoop.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.africascoop.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.africascoop.net\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.africascoop.net\/index.php\/wp-json\/wp\/v2\/comments?post=1890"}],"version-history":[{"count":1,"href":"https:\/\/www.africascoop.net\/index.php\/wp-json\/wp\/v2\/posts\/1890\/revisions"}],"predecessor-version":[{"id":1892,"href":"https:\/\/www.africascoop.net\/index.php\/wp-json\/wp\/v2\/posts\/1890\/revisions\/1892"}],"wp:attachment":[{"href":"https:\/\/www.africascoop.net\/index.php\/wp-json\/wp\/v2\/media?parent=1890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.africascoop.net\/index.php\/wp-json\/wp\/v2\/categories?post=1890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.africascoop.net\/index.php\/wp-json\/wp\/v2\/tags?post=1890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}